{"id":61769,"date":"2021-03-25T19:30:32","date_gmt":"2021-03-25T19:30:32","guid":{"rendered":"http:\/\/decodeonlineshop.com\/wordpress\/?page_id=61769"},"modified":"2021-04-01T12:11:27","modified_gmt":"2021-04-01T12:11:27","slug":"carpets-for-livingroom","status":"publish","type":"page","link":"https:\/\/decodeonlineshop.com\/wordpress\/carpets-for-livingroom\/","title":{"rendered":"CARPETS FOR LIVINGROOM"},"content":{"rendered":"\n<a class=\"titlearray\" href=\"http:\/\/decodeonlineshop.com\/wordpress\/product-category\/carpets\/\">Carpets<\/a>\n<a class=\"titlearray\">\/<\/a>\n<a class=\"titlearray titleend\">CARPETS FOR LIVINGROOM<\/a>\n<style>\nh1.entry-title{\ndisplay:none;\n}\n<\/style>\n\n\n<div class=\"woocommerce columns-4 \"><div class=\"woocommerce-notices-wrapper\"><\/div><p class=\"woocommerce-result-count\" role=\"status\" aria-relevant=\"all\" >\n\tShowing all 65 results<\/p>\n<form class=\"woocommerce-ordering\" method=\"get\">\n\t\t<select\n\t\tname=\"orderby\"\n\t\tclass=\"orderby\"\n\t\t\t\t\taria-label=\"Shop order\"\n\t\t\t>\n\t\t\t\t\t<option value=\"menu_order\"  selected='selected'>Default sorting<\/option>\n\t\t\t\t\t<option value=\"popularity\" >Sort by popularity<\/option>\n\t\t\t\t\t<option value=\"date\" >Sort by latest<\/option>\n\t\t\t\t\t<option value=\"price\" >Sort by price: low to high<\/option>\n\t\t\t\t\t<option value=\"price-desc\" >Sort by price: high to low<\/option>\n\t\t\t<\/select>\n\t<input type=\"hidden\" name=\"paged\" value=\"1\" \/>\n\t<\/form>\n<ul class=\"products columns-4\">\n<li class=\"item-prod-wrap wow flipInY product type-product post-117448 status-publish first instock product_cat-carpets product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/austin-teppich\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/28192-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/28192-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/28192-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/28192-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/28192-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/28192-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/28192-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/28192-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/28192-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/28192.png 567w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Austin Teppich<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117448\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117448\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117448\" data-product_sku=\"LA-70829\" aria-label=\"Add to cart: &ldquo;Austin Teppich&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Austin Teppich&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117448\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,229.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117453 status-publish instock product_cat-carpets product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/buffalo-teppich\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27395-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27395-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27395-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27395-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27395-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27395-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27395-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27395-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27395-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27395.png 529w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Buffalo Teppich<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117453\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117453\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117453\" data-product_sku=\"LA-70820\" aria-label=\"Add to cart: &ldquo;Buffalo Teppich&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Buffalo Teppich&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117453\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,194.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117458 status-publish instock product_cat-carpets product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/buffalo-teppich-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27397-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27397-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27397-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27397-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27397-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27397-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27397-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27397-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27397-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27397.png 529w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Buffalo Teppich<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117458\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117458\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117458\" data-product_sku=\"LA-70821\" aria-label=\"Add to cart: &ldquo;Buffalo Teppich&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Buffalo Teppich&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117458\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,647.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117463 status-publish last instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-abbot-natural\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37102-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37102-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37102-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37102-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37102-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37102-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Abbot Natural<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117463\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117463\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117463\" data-product_sku=\"EH-109267\" aria-label=\"Add to cart: &ldquo;Carpet Abbot Natural&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Abbot Natural&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117463\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,330.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117464 status-publish first instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-abbot-natural-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37105-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37105-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37105-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37105-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37105-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37105-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Abbot Natural<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117464\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117464\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117464\" data-product_sku=\"EH-109268\" aria-label=\"Add to cart: &ldquo;Carpet Abbot Natural&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Abbot Natural&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117464\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,950.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117465 status-publish instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-abbot-natural-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37108-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37108-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37108-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37108-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37108-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37108-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Abbot Natural<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117465\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117465\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117465\" data-product_sku=\"EH-109269\" aria-label=\"Add to cart: &ldquo;Carpet Abbot Natural&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Abbot Natural&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117465\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3,900.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117466 status-publish outofstock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-apollo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22764-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22764-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22764-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22764-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22764-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22764-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22764-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22764-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22764-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22764-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22764-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22764.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Apollo<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-apollo\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117466\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"117466\" data-product_sku=\"EH-108536\" aria-label=\"Read more about &ldquo;Carpet Apollo&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117466\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,130.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117467 status-publish last outofstock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-apollo-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22766-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22766-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22766-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22766-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22766-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22766-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22766-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22766-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22766-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22766-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22766-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22766.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Apollo<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-apollo-2\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117467\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"117467\" data-product_sku=\"EH-108537\" aria-label=\"Read more about &ldquo;Carpet Apollo&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117467\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>2,460.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117468 status-publish first outofstock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-apollo-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22768-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22768-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22768-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22768-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22768-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22768-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22768-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22768-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22768-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22768-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22768-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22768.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Apollo<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-apollo-3\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117468\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"117468\" data-product_sku=\"EH-108538\" aria-label=\"Read more about &ldquo;Carpet Apollo&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117468\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3,280.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117469 status-publish outofstock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-baldwin-sapphire\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37126-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37126-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37126-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37126-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37126-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37126-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Baldwin Sapphire<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-baldwin-sapphire\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117469\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"117469\" data-product_sku=\"EH-109275\" aria-label=\"Read more about &ldquo;Carpet Baldwin Sapphire&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117469\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,130.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117470 status-publish instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-baldwin-sapphire-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37129-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37129-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37129-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37129-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37129-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37129-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Baldwin Sapphire<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117470\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117470\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117470\" data-product_sku=\"EH-109276\" aria-label=\"Add to cart: &ldquo;Carpet Baldwin Sapphire&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Baldwin Sapphire&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117470\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,950.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117471 status-publish last instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-baldwin-sapphire-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37132-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37132-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37132-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37132-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37132-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37132-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Baldwin Sapphire<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117471\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117471\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117471\" data-product_sku=\"EH-109277\" aria-label=\"Add to cart: &ldquo;Carpet Baldwin Sapphire&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Baldwin Sapphire&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117471\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3,900.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117472 status-publish first outofstock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-burban\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22823-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22823-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22823-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22823-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22823-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22823-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22823-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22823-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22823-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22823-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22823-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22823.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Burban<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-burban\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117472\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"117472\" data-product_sku=\"EH-108517\" aria-label=\"Read more about &ldquo;Carpet Burban&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117472\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,130.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117473 status-publish outofstock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-burban-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22826-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22826-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22826-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22826-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22826-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22826-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22826-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22826-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22826-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22826-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22826-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22826.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Burban<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-burban-2\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117473\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"117473\" data-product_sku=\"EH-108518\" aria-label=\"Read more about &ldquo;Carpet Burban&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117473\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,640.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117474 status-publish instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-burban-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22829-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22829-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22829-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22829-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22829-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22829-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22829-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22829-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22829-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22829-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22829-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22829.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Burban<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117474\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117474\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117474\" data-product_sku=\"EH-108519\" aria-label=\"Add to cart: &ldquo;Carpet Burban&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Burban&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117474\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3,900.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117475 status-publish last outofstock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-caton\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22798-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22798-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22798-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22798-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22798-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22798-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22798-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22798-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22798-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22798-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22798-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22798.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Caton<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-caton\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117475\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"117475\" data-product_sku=\"EH-108527\" aria-label=\"Read more about &ldquo;Carpet Caton&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117475\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>2,460.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117476 status-publish first outofstock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-caton-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22807-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22807-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22807-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22807-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22807-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22807-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22807-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22807-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22807-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22807-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22807-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22807.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Caton<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-caton-2\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117476\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"117476\" data-product_sku=\"EH-108524\" aria-label=\"Read more about &ldquo;Carpet Caton&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117476\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>2,460.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117477 status-publish outofstock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-caton-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22810-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22810-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22810-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22810-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22810-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22810-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22810-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22810-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22810-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22810-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22810-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22810.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Caton<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-caton-3\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117477\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"117477\" data-product_sku=\"EH-108525\" aria-label=\"Read more about &ldquo;Carpet Caton&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117477\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3,280.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117478 status-publish outofstock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-celeste\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42722-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42722-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42722-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42722-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42722-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42722-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Celeste<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-celeste\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117478\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"117478\" data-product_sku=\"EH-109763\" aria-label=\"Read more about &ldquo;Carpet Celeste&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117478\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,130.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117479 status-publish last instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-celeste-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43093-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43093-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43093-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43093-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43093-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43093-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Celeste<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117479\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117479\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117479\" data-product_sku=\"EH-109764\" aria-label=\"Add to cart: &ldquo;Carpet Celeste&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Celeste&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117479\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,950.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117480 status-publish first instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-celeste-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43098-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43098-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43098-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43098-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43098-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43098-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Celeste<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117480\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117480\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117480\" data-product_sku=\"EH-109765\" aria-label=\"Add to cart: &ldquo;Carpet Celeste&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Celeste&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117480\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3,900.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117481 status-publish instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-diabolo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22884-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22884-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22884-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22884-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22884-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22884-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22884-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22884-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22884-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22884-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22884-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22884.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Diabolo<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117481\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117481\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117481\" data-product_sku=\"EH-108499\" aria-label=\"Add to cart: &ldquo;Carpet Diabolo&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Diabolo&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117481\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,950.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117482 status-publish instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-evans\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43075-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43075-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43075-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43075-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43075-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43075-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Evans<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117482\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117482\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117482\" data-product_sku=\"EH-109767\" aria-label=\"Add to cart: &ldquo;Carpet Evans&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Evans&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117482\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,950.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117483 status-publish last instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-evans-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43080-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43080-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43080-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43080-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43080-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43080-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Evans<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117483\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117483\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117483\" data-product_sku=\"EH-109766\" aria-label=\"Add to cart: &ldquo;Carpet Evans&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Evans&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117483\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,330.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117484 status-publish first instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-evans-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43083-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43083-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43083-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43083-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43083-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43083-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Evans<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117484\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117484\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117484\" data-product_sku=\"EH-109768\" aria-label=\"Add to cart: &ldquo;Carpet Evans&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Evans&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117484\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3,900.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117485 status-publish instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-george\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43172-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43172-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43172-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43172-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43172-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43172-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet George<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117485\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117485\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117485\" data-product_sku=\"EH-109758\" aria-label=\"Add to cart: &ldquo;Carpet George&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet George&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117485\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,330.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117486 status-publish instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-george-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43175-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43175-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43175-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43175-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43175-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43175-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet George<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117486\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117486\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117486\" data-product_sku=\"EH-109759\" aria-label=\"Add to cart: &ldquo;Carpet George&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet George&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117486\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,950.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117487 status-publish last instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-george-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43178-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43178-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43178-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43178-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43178-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43178-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet George<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117487\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117487\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117487\" data-product_sku=\"EH-109760\" aria-label=\"Add to cart: &ldquo;Carpet George&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet George&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117487\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3,900.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117488 status-publish first instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-harris\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42716-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42716-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42716-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42716-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42716-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42716-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Harris<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117488\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117488\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117488\" data-product_sku=\"EH-109750\" aria-label=\"Add to cart: &ldquo;Carpet Harris&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Harris&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117488\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,950.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117489 status-publish instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-harris-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42719-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42719-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42719-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42719-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42719-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42719-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Harris<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117489\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117489\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117489\" data-product_sku=\"EH-109753\" aria-label=\"Add to cart: &ldquo;Carpet Harris&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Harris&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117489\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,950.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117490 status-publish instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-harris-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43138-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43138-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43138-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43138-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43138-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43138-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Harris<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117490\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117490\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117490\" data-product_sku=\"EH-109749\" aria-label=\"Add to cart: &ldquo;Carpet Harris&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Harris&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117490\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,330.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117491 status-publish last instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-harris-4\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43141-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43141-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43141-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43141-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43141-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43141-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Harris<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117491\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117491\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117491\" data-product_sku=\"EH-109751\" aria-label=\"Add to cart: &ldquo;Carpet Harris&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Harris&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117491\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3,900.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117492 status-publish first instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-harris-5\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43144-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43144-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43144-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43144-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43144-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43144-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Harris<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117492\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117492\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117492\" data-product_sku=\"EH-109752\" aria-label=\"Add to cart: &ldquo;Carpet Harris&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Harris&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117492\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,330.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117493 status-publish instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-harris-6\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43147-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43147-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43147-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43147-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43147-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43147-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Harris<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117493\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117493\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117493\" data-product_sku=\"EH-109754\" aria-label=\"Add to cart: &ldquo;Carpet Harris&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Harris&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117493\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3,900.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117494 status-publish outofstock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-owens-ruby\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37120-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37120-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37120-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37120-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37120-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37120-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Owens Ruby<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-owens-ruby\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117494\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"117494\" data-product_sku=\"EH-109273\" aria-label=\"Read more about &ldquo;Carpet Owens Ruby&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117494\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,400.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117495 status-publish last instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-sakura\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42725-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42725-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42725-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42725-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42725-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/42725-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Sakura<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117495\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117495\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117495\" data-product_sku=\"EH-109762\" aria-label=\"Add to cart: &ldquo;Carpet Sakura&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Sakura&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117495\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,830.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117496 status-publish first instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-shaw\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/41334-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/41334-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/41334-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/41334-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/41334-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/41334-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Shaw<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117496\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117496\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117496\" data-product_sku=\"EH-109609\" aria-label=\"Add to cart: &ldquo;Carpet Shaw&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Shaw&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117496\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,130.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117497 status-publish outofstock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-shaw-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43152-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43152-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43152-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43152-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43152-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43152-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Shaw<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-shaw-2\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117497\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"117497\" data-product_sku=\"EH-109610\" aria-label=\"Read more about &ldquo;Carpet Shaw&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117497\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,640.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117498 status-publish instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-shaw-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43155-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43155-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43155-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43155-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43155-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43155-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Shaw<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117498\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117498\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117498\" data-product_sku=\"EH-109611\" aria-label=\"Add to cart: &ldquo;Carpet Shaw&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Shaw&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117498\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3,900.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117499 status-publish last instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-thistle\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22854-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22854-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22854-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22854-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22854-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22854-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22854-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22854-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22854-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22854-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22854-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22854.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Thistle<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117499\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117499\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117499\" data-product_sku=\"EH-108510\" aria-label=\"Add to cart: &ldquo;Carpet Thistle&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Thistle&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117499\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>2,440.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117500 status-publish first instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-thistle-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22857-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22857-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22857-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22857-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22857-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22857-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22857-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22857-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22857-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22857-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22857-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/22857.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Thistle<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117500\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117500\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117500\" data-product_sku=\"EH-108507\" aria-label=\"Add to cart: &ldquo;Carpet Thistle&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Thistle&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117500\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,330.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117501 status-publish instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-voyage\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/43181-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/43181-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/43181-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/43181-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/43181-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/43181-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Voyage<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117501\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117501\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117501\" data-product_sku=\"EH-109761\" aria-label=\"Add to cart: &ldquo;Carpet Voyage&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Voyage&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117501\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,590.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117506 status-publish outofstock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-warner-aqua\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37093-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37093-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37093-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37093-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37093-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37093-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Warner Aqua<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-warner-aqua\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117506\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"117506\" data-product_sku=\"EH-109261\" aria-label=\"Read more about &ldquo;Carpet Warner Aqua&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117506\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,130.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117507 status-publish last outofstock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-warner-aqua-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37096-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37096-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37096-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37096-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37096-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37096-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Warner Aqua<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-warner-aqua-2\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117507\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"117507\" data-product_sku=\"EH-109262\" aria-label=\"Read more about &ldquo;Carpet Warner Aqua&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117507\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,640.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117508 status-publish first instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-warner-aqua-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37099-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37099-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37099-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37099-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37099-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37099-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Warner Aqua<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117508\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117508\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117508\" data-product_sku=\"EH-109263\" aria-label=\"Add to cart: &ldquo;Carpet Warner Aqua&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Warner Aqua&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117508\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3,900.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117509 status-publish instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-webb\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43162-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43162-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43162-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43162-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43162-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43162-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Webb<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117509\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117509\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117509\" data-product_sku=\"EH-109607\" aria-label=\"Add to cart: &ldquo;Carpet Webb&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Webb&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117509\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,950.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117510 status-publish instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-webb-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43165-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43165-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43165-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43165-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43165-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/43165-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Webb<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117510\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117510\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117510\" data-product_sku=\"EH-109608\" aria-label=\"Add to cart: &ldquo;Carpet Webb&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Webb&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117510\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3,900.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117511 status-publish last outofstock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-wilton-feather\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37145-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37145-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37145-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37145-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37145-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37145-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Wilton Feather<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-wilton-feather\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117511\" data-quantity=\"1\" class=\"button product_type_simple\" data-product_id=\"117511\" data-product_sku=\"EH-109264\" aria-label=\"Read more about &ldquo;Carpet Wilton Feather&rdquo;\" rel=\"nofollow\" data-success_message=\"\">Read more<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117511\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,130.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117512 status-publish first instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-wilton-feather-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37148-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37148-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37148-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37148-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37148-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37148-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Wilton Feather<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117512\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117512\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117512\" data-product_sku=\"EH-109265\" aria-label=\"Add to cart: &ldquo;Carpet Wilton Feather&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Wilton Feather&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117512\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,950.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117513 status-publish instock product_cat-carpets product_cat-eichholtz product_cat-for-bedroom product_cat-for-livingroom has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/carpet-wilton-feather-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37159-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37159-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37159-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37159-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37159-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/05\/37159-100x100.png 100w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Carpet Wilton Feather<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117513\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117513\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117513\" data-product_sku=\"EH-109266\" aria-label=\"Add to cart: &ldquo;Carpet Wilton Feather&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Carpet Wilton Feather&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117513\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>3,900.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117514 status-publish instock product_cat-carpets product_cat-for-bedroom product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/essauira-berberteppich\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27381-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27381-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27381-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27381-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27381-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27381-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27381-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27381-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27381-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27381-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27381-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27381.png 872w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Essauira Berberteppich<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117514\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117514\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117514\" data-product_sku=\"LA-70710\" aria-label=\"Add to cart: &ldquo;Essauira Berberteppich&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Essauira Berberteppich&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117514\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,225.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117519 status-publish last instock product_cat-carpets product_cat-for-bedroom product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/essauira-berberteppich-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27384-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27384-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27384-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27384-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27384-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27384-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27384-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27384-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27384-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27384-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27384-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27384.png 872w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Essauira Berberteppich<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117519\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117519\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117519\" data-product_sku=\"LA-70712\" aria-label=\"Add to cart: &ldquo;Essauira Berberteppich&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Essauira Berberteppich&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117519\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>2,109.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117524 status-publish first instock product_cat-carpets product_cat-for-bedroom product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/lhasa-teppich\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27370-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27370-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27370-1024x1024.png 1024w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27370-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27370-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27370-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27370-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27370-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27370-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27370-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27370-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27370-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27370.png 1121w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Lhasa Teppich<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117524\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117524\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117524\" data-product_sku=\"LA-70781\" aria-label=\"Add to cart: &ldquo;Lhasa Teppich&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Lhasa Teppich&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117524\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,915.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117529 status-publish instock product_cat-carpets product_cat-for-bedroom product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/lhasa-teppich-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27373-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27373-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27373-1024x1024.png 1024w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27373-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27373-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27373-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27373-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27373-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27373-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27373-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27373-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27373-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27373.png 1121w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Lhasa Teppich<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117529\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117529\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117529\" data-product_sku=\"LA-70782\" aria-label=\"Add to cart: &ldquo;Lhasa Teppich&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Lhasa Teppich&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117529\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>2,825.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117534 status-publish instock product_cat-carpets product_cat-for-bedroom product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/lhasa-teppich-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27375-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27375-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27375-1024x1024.png 1024w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27375-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27375-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27375-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27375-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27375-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27375-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27375-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27375-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27375-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27375.png 1121w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Lhasa Teppich<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117534\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117534\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117534\" data-product_sku=\"LA-70785\" aria-label=\"Add to cart: &ldquo;Lhasa Teppich&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Lhasa Teppich&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117534\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,885.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117539 status-publish last instock product_cat-carpets product_cat-for-bedroom product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/lhasa-teppich-4\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27377-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27377-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27377-1024x1024.png 1024w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27377-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27377-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27377-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27377-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27377-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27377-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27377-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27377-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27377-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27377.png 1121w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Lhasa Teppich<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117539\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117539\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117539\" data-product_sku=\"LA-70786\" aria-label=\"Add to cart: &ldquo;Lhasa Teppich&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Lhasa Teppich&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117539\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,915.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117544 status-publish first instock product_cat-carpets product_cat-for-bedroom product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/lhasa-teppich-5\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27379-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27379-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27379-1024x1024.png 1024w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27379-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27379-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27379-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27379-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27379-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27379-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27379-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27379-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27379-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27379.png 1121w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Lhasa Teppich<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117544\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117544\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117544\" data-product_sku=\"LA-70790\" aria-label=\"Add to cart: &ldquo;Lhasa Teppich&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Lhasa Teppich&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117544\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,885.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117549 status-publish instock product_cat-carpets product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/ontario-teppich-rinderfell-mosaik\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27386-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27386-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27386-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27386-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27386-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27386-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27386-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27386-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27386-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27386-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27386-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27386.png 886w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Ontario Teppich Rinderfell Mosaik<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117549\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117549\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117549\" data-product_sku=\"LA-70800\" aria-label=\"Add to cart: &ldquo;Ontario Teppich Rinderfell Mosaik&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Ontario Teppich Rinderfell Mosaik&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117549\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,060.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117554 status-publish instock product_cat-carpets product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/ontario-teppich-rinderfell-mosaik-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27389-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27389-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27389-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27389-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27389-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27389-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27389-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27389-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27389-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27389-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27389-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27389.png 886w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Ontario Teppich Rinderfell Mosaik<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117554\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117554\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117554\" data-product_sku=\"LA-70804\" aria-label=\"Add to cart: &ldquo;Ontario Teppich Rinderfell Mosaik&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Ontario Teppich Rinderfell Mosaik&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117554\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>1,060.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117559 status-publish last instock product_cat-carpets product_cat-for-bedroom product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/pampa-teppich\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27357-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27357-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27357-1024x1024.png 1024w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27357-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27357-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27357-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27357-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27357-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27357-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27357-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27357-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27357-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27357.png 1476w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Pampa Teppich<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117559\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117559\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117559\" data-product_sku=\"LA-74240\" aria-label=\"Add to cart: &ldquo;Pampa Teppich&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Pampa Teppich&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117559\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>765.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117564 status-publish first instock product_cat-carpets product_cat-for-bedroom product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/pampa-teppich-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27360-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27360-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27360-1024x1024.png 1024w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27360-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27360-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27360-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27360-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27360-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27360-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27360-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27360-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27360-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27360.png 1476w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Pampa Teppich<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117564\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117564\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117564\" data-product_sku=\"LA-74241\" aria-label=\"Add to cart: &ldquo;Pampa Teppich&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Pampa Teppich&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117564\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>765.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117569 status-publish instock product_cat-carpets product_cat-for-bedroom product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/pampa-teppich-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27362-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27362-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27362-1024x1024.png 1024w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27362-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27362-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27362-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27362-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27362-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27362-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27362-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27362-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27362-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27362.png 1350w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Pampa Teppich<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117569\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117569\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117569\" data-product_sku=\"LA-74242\" aria-label=\"Add to cart: &ldquo;Pampa Teppich&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Pampa Teppich&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117569\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>765.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117574 status-publish instock product_cat-carpets product_cat-for-bedroom product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/pampa-teppich-4\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27364-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27364-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27364-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27364-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27364-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27364-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27364-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27364-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27364-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27364-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27364-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27364.png 1007w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Pampa Teppich<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117574\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117574\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117574\" data-product_sku=\"LA-74243\" aria-label=\"Add to cart: &ldquo;Pampa Teppich&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Pampa Teppich&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117574\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>765.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117579 status-publish last instock product_cat-carpets product_cat-for-bedroom product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/pampa-teppich-5\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27366-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27366-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27366-1024x1024.png 1024w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27366-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27366-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27366-1536x1536.png 1536w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27366-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27366-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27366-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27366-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27366-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27366-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27366-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27366.png 1542w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Pampa Teppich<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117579\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117579\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117579\" data-product_sku=\"LA-74244\" aria-label=\"Add to cart: &ldquo;Pampa Teppich&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Pampa Teppich&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117579\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>765.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><li class=\"item-prod-wrap wow flipInY product type-product post-117584 status-publish first instock product_cat-carpets product_cat-for-bedroom product_cat-for-livingroom product_cat-lambert has-post-thumbnail purchasable product-type-simple\">\n    \n    <div class=\"collection_combine item-img\">\n        <a href=\"https:\/\/decodeonlineshop.com\/wordpress\/product\/pampa-teppich-6\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">        <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27368-300x300.png\" class=\"attachment-shop_catalog size-shop_catalog wp-post-image\" alt=\"\" srcset=\"https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27368-300x300.png 300w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27368-1024x1024.png 1024w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27368-150x150.png 150w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27368-768x768.png 768w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27368-520x520.png 520w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27368-70x70.png 70w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27368-24x24.png 24w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27368-36x36.png 36w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27368-48x48.png 48w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27368-600x600.png 600w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27368-100x100.png 100w, https:\/\/decodeonlineshop.com\/wordpress\/wp-content\/uploads\/2021\/08\/27368.png 1476w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>                    <\/div>\n        <div class=\"collection_desc clearfix\">\n            <div class=\"title-cart\">\n\t\t\t\t<h3>Pampa Teppich<\/h3>\n                <div class=\"cart\">\n                    <\/a><a href=\"\/wordpress\/wp-json\/wp\/v2\/pages\/61769?add-to-cart=117584\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_117584\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"117584\" data-product_sku=\"LA-74245\" aria-label=\"Add to cart: &ldquo;Pampa Teppich&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;Pampa Teppich&rdquo; has been added to your cart\" role=\"button\">Add to cart<\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_117584\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n        <\/div>\n    <\/div>\n    <div class=\"price-desc\">\n        \n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span>765.00<\/bdi><\/span><\/span>\n        <\/div>\n    <\/div>\n<\/li><\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Carpets \/ CARPETS FOR LIVINGROOM<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-61769","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/decodeonlineshop.com\/wordpress\/wp-json\/wp\/v2\/pages\/61769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decodeonlineshop.com\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/decodeonlineshop.com\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/decodeonlineshop.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/decodeonlineshop.com\/wordpress\/wp-json\/wp\/v2\/comments?post=61769"}],"version-history":[{"count":3,"href":"https:\/\/decodeonlineshop.com\/wordpress\/wp-json\/wp\/v2\/pages\/61769\/revisions"}],"predecessor-version":[{"id":62168,"href":"https:\/\/decodeonlineshop.com\/wordpress\/wp-json\/wp\/v2\/pages\/61769\/revisions\/62168"}],"wp:attachment":[{"href":"https:\/\/decodeonlineshop.com\/wordpress\/wp-json\/wp\/v2\/media?parent=61769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}